{"id":1110,"date":"2024-04-10T21:13:53","date_gmt":"2024-04-10T21:13:53","guid":{"rendered":"https:\/\/revistaatenea.com\/?p=1110"},"modified":"2024-04-10T21:14:04","modified_gmt":"2024-04-10T21:14:04","slug":"anel-banos-duran-asertiva-y-lider-nata","status":"publish","type":"post","link":"https:\/\/revistaatenea.com\/index.php\/2024\/04\/10\/anel-banos-duran-asertiva-y-lider-nata\/","title":{"rendered":"<strong><em>Anel Ba\u00f1os Duran: asertiva y l\u00edder nata<\/em><\/strong>"},"content":{"rendered":"\n<p>Una profesionista de alto nivel, responsable, comprometida y altamente eficiente para concretar operaciones exitosas en el tema inmobiliario.<\/p>\n\n\n\n<p>La responsabilidad, el profesionalismo y la \u00e9tica son pilares de su vida, su persona y su trabajo, juntos estos valores, han hecho que Anel Ba\u00f1os trascienda en todas las facetas de su vida y que se afiance con gran respeto en el gremio al que pertenece.<\/p>\n\n\n\n<p>En su ramo, las mujeres son quienes toman las decisiones de adquirir valores inmobiliarios, ellas son las de la \u00faltima palabra y para Anel, esto es significado de la relevancia que tiene la mujer en las mejores negociaciones.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201c Somos afortunadas de vivir este proceso de cambio que nuestras antepasadas no pudieron ver, hoy estamos aprendiendo a reconocer nuestras capacidades y a visualizar el papel tan importante que jugamos en la sociedad \u201d.<\/p>\n<\/blockquote>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p><strong><em>Poder Atenea: H\u00e1bil negociadora y comprometida profesional<\/em><\/strong><\/p><\/blockquote><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Una profesionista de alto nivel, responsable, comprometida y altamente eficiente para concretar operaciones exitosas en el tema inmobiliario. La responsabilidad, el profesionalismo y la \u00e9tica son pilares de su vida,&hellip; <\/p>\n","protected":false},"author":6,"featured_media":1111,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"two_page_speed":[],"footnotes":""},"categories":[344],"tags":[362,365],"class_list":["post-1110","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-liderazgo","tag-liderazgo","tag-mujeres-atenea"],"_links":{"self":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts\/1110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/comments?post=1110"}],"version-history":[{"count":2,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts\/1110\/revisions"}],"predecessor-version":[{"id":1193,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts\/1110\/revisions\/1193"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/media\/1111"}],"wp:attachment":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/media?parent=1110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/categories?post=1110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/tags?post=1110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}