{"id":1134,"date":"2024-04-10T23:24:22","date_gmt":"2024-04-10T23:24:22","guid":{"rendered":"https:\/\/revistaatenea.com\/?p=1134"},"modified":"2024-04-10T23:24:33","modified_gmt":"2024-04-10T23:24:33","slug":"fabiola-reyes-millan-construyendo-para-el-futuro","status":"publish","type":"post","link":"https:\/\/revistaatenea.com\/index.php\/2024\/04\/10\/fabiola-reyes-millan-construyendo-para-el-futuro\/","title":{"rendered":"<strong><em>Fabiola Reyes Mill\u00e1n: Construyendo para el futuro<\/em><\/strong>"},"content":{"rendered":"\n<p>Fabiola Reyes Mill\u00e1n, empresaria y fundadora de Grupo Comercial JIRE, no solo es una visionaria en el mundo de los negocios, sino tambi\u00e9n una luchadora incansable como miembro destacado de la asociaci\u00f3n TSC Alliance de esclerosis tuberosa.<\/p>\n\n\n\n<p>Su dedicaci\u00f3n a mejorar la vida de las personas afectadas por esta enfermedad demuestra su car\u00e1cter trabajador, responsable, amoroso y, sobre todo, emp\u00e1tico, pues su perspectiva ha evolucionado desde que este padecimiento alcanz\u00f3 a su hijo.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Fabiola reconoce el papel fundamental de las mujeres en la sociedad, pues las considera como la base de todo. Ella enfatiza que la mujer, como educadora principal en la familia, tiene el poder de influir en la formaci\u00f3n de futuras generaciones, y que las decisiones que tomen como cabezas de familia sin duda afectar\u00e1 a otros ciudadanos. Destaca la importancia de educar en la igualdad y el respeto para construir una sociedad m\u00e1s justa y equitativa.<\/p>\n<\/blockquote>\n\n\n\n<p>Fabiola tambi\u00e9n destaca la importancia de equilibrar la responsabilidad de la crianza y las labores empresariales con el amor propio. Nos insta a nunca dejar de valorarnos y creer en nuestras capacidades. Nos recuerda que los sue\u00f1os son alcanzables si persistimos en nuestro esfuerzo y dedicaci\u00f3n. Para ella, el conocimiento es la verdadera fortaleza que nos impulsa a superar cualquier obst\u00e1culo en el camino hacia nuestros objetivos.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p><strong><em>Poder Atenea: Visionaria en los negocios\u00a0<\/em><\/strong><\/p><\/blockquote><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Fabiola Reyes Mill\u00e1n, empresaria y fundadora de Grupo Comercial JIRE, no solo es una visionaria en el mundo de los negocios, sino tambi\u00e9n una luchadora incansable como miembro destacado de&hellip; <\/p>\n","protected":false},"author":8,"featured_media":1135,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"two_page_speed":[],"footnotes":""},"categories":[344],"tags":[362,365],"class_list":["post-1134","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-liderazgo","tag-liderazgo","tag-mujeres-atenea"],"_links":{"self":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts\/1134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/comments?post=1134"}],"version-history":[{"count":2,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts\/1134\/revisions"}],"predecessor-version":[{"id":1211,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts\/1134\/revisions\/1211"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/media\/1135"}],"wp:attachment":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/media?parent=1134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/categories?post=1134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/tags?post=1134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}