{"id":1143,"date":"2024-04-10T23:47:49","date_gmt":"2024-04-10T23:47:49","guid":{"rendered":"https:\/\/revistaatenea.com\/?p=1143"},"modified":"2024-04-10T23:48:01","modified_gmt":"2024-04-10T23:48:01","slug":"pau-conde-agente-de-cambio-y-empoderamiento","status":"publish","type":"post","link":"https:\/\/revistaatenea.com\/index.php\/2024\/04\/10\/pau-conde-agente-de-cambio-y-empoderamiento\/","title":{"rendered":"Pau Conde: agente de cambio y empoderamiento"},"content":{"rendered":"\n<p>Paulina Conde Lugo, dise\u00f1adora de negocios y eventos, es la mente maestra detr\u00e1s de Tapai Coworking y Come y Calla, una agencia de eventos que destaca por su enfoque en la comida y el ambiente. Su creatividad, su energ\u00eda contagiosa y su risa son las se\u00f1as de identidad que la definen.<\/p>\n\n\n\n<p><strong><em>Afirma que las mujeres son un agente de cambio y empoderamiento. Cree firmemente en la importancia de desafiar los paradigmas y prejuicios de g\u00e9nero, y en materializar la igualdad de oportunidades para las mujeres y ni\u00f1as.<\/em><\/strong><\/p>\n\n\n\n<p>Pau nos recuerda la responsabilidad que conlleva el poder que poseemos como mujeres para usarlo siempre en nuestro beneficio y a compartirlo con quienes nos rodean.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p><em><strong>Poder Atenea: Dise\u00f1adora de negocios y eventos<\/strong><\/em><\/p><\/blockquote><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Paulina Conde Lugo, dise\u00f1adora de negocios y eventos, es la mente maestra detr\u00e1s de Tapai Coworking y Come y Calla, una agencia de eventos que destaca por su enfoque en&hellip; <\/p>\n","protected":false},"author":8,"featured_media":1144,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"two_page_speed":[],"footnotes":""},"categories":[344],"tags":[362,365],"class_list":["post-1143","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-liderazgo","tag-liderazgo","tag-mujeres-atenea"],"_links":{"self":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts\/1143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/comments?post=1143"}],"version-history":[{"count":2,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts\/1143\/revisions"}],"predecessor-version":[{"id":1216,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts\/1143\/revisions\/1216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/media\/1144"}],"wp:attachment":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/media?parent=1143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/categories?post=1143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/tags?post=1143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}