{"id":1173,"date":"2024-04-11T00:31:02","date_gmt":"2024-04-11T00:31:02","guid":{"rendered":"https:\/\/revistaatenea.com\/?p=1173"},"modified":"2024-04-11T00:31:04","modified_gmt":"2024-04-11T00:31:04","slug":"fabiola-tellez-ramirez-inspiracion-y-fortaleza-en-la-medicina","status":"publish","type":"post","link":"https:\/\/revistaatenea.com\/index.php\/2024\/04\/11\/fabiola-tellez-ramirez-inspiracion-y-fortaleza-en-la-medicina\/","title":{"rendered":"<strong><em>Fabiola T\u00e9llez Ram\u00edrez: Inspiraci\u00f3n y fortaleza en la Medicina<\/em><\/strong>"},"content":{"rendered":"\n<p>Con 19 a\u00f1os de trayectoria como m\u00e9dico cirujano, Fabiola T\u00e9llez Ram\u00edrez es un ejemplo vivo de la fuerza y la dedicaci\u00f3n que las mujeres aportan al campo de la medicina. Originaria de Real del Monte, ha ejercido tanto en su consultorio privado en esta localidad como en Pachuca, donde tambi\u00e9n tiene su propia pr\u00e1ctica m\u00e9dica.<\/p>\n\n\n\n<p>Para Fabiola, ser mujer en la Medicina es un privilegio. <em><strong>Considera que las mujeres tienen un sentido innato de ayuda y servicio que les permite entender mejor las necesidades de quien lo necesite.<\/strong><\/em><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>A lo largo de su carrera, Fabiola ha tenido la oportunidad de desempe\u00f1arse en diversos roles, desde coordinadora del \u00e1rea m\u00e9dica del DIF Pachuca hasta coordinadora de unidades m\u00f3viles del gobierno del Estado. Gracias a su capacidad organizativa y social.<\/p>\n<\/blockquote>\n\n\n\n<p>Considera que las mujeres representan la lucha, la entrega y la fuerza que se necesitan para salir adelante en cualquier aspecto de la vida.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p><strong><em>Poder Atenea: Fortaleza y determinaci\u00f3n dentro de la medicina.<\/em><\/strong><\/p><\/blockquote><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Con 19 a\u00f1os de trayectoria como m\u00e9dico cirujano, Fabiola T\u00e9llez Ram\u00edrez es un ejemplo vivo de la fuerza y la dedicaci\u00f3n que las mujeres aportan al campo de la medicina.&hellip; <\/p>\n","protected":false},"author":8,"featured_media":1174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"two_page_speed":[],"footnotes":""},"categories":[344],"tags":[362,365],"class_list":["post-1173","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-liderazgo","tag-liderazgo","tag-mujeres-atenea"],"_links":{"self":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts\/1173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/comments?post=1173"}],"version-history":[{"count":2,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts\/1173\/revisions"}],"predecessor-version":[{"id":1212,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts\/1173\/revisions\/1212"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/media\/1174"}],"wp:attachment":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/media?parent=1173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/categories?post=1173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/tags?post=1173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}