{"id":1803,"date":"2025-11-21T22:09:05","date_gmt":"2025-11-21T22:09:05","guid":{"rendered":"https:\/\/revistaatenea.com\/?p=1803"},"modified":"2025-11-21T22:09:10","modified_gmt":"2025-11-21T22:09:10","slug":"karen-riquelme","status":"publish","type":"post","link":"https:\/\/revistaatenea.com\/index.php\/2025\/11\/21\/karen-riquelme\/","title":{"rendered":"Karen Riquelme"},"content":{"rendered":"\n<p><strong>L\u00edder de MG Nails SPA<\/strong> <strong>Karen es licenciada en Mercadotecnia y l\u00edder de MG Nails SPA, una marca que ha elevado los est\u00e1ndares en el cuidado de manos y pies.<\/strong><\/p>\n\n\n\n<p><strong>Apasionada, comprometida y en constante evoluci\u00f3n<\/strong>, Karen disfruta viajar, compartir con su familia y superar retos.<\/p>\n\n\n\n<p><strong>Ser mam\u00e1 es su mayor motor y desde ah\u00ed construye con valores y ejemplo. Cree en la excelencia, el detalle y en dejar huella impulsando a otras mujeres.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u00edder de MG Nails SPA Karen es licenciada en Mercadotecnia y l\u00edder de MG Nails SPA, una marca que ha elevado los est\u00e1ndares en el cuidado de manos y pies.&hellip; <\/p>\n","protected":false},"author":9,"featured_media":1804,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"two_page_speed":[],"footnotes":""},"categories":[358],"tags":[362,120,365,20],"class_list":["post-1803","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mujeres","tag-liderazgo","tag-mujeres","tag-mujeres-atenea","tag-pachuca"],"_links":{"self":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts\/1803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/comments?post=1803"}],"version-history":[{"count":1,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts\/1803\/revisions"}],"predecessor-version":[{"id":1805,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts\/1803\/revisions\/1805"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/media\/1804"}],"wp:attachment":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/media?parent=1803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/categories?post=1803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/tags?post=1803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}