{"id":292,"date":"2023-03-08T17:38:36","date_gmt":"2023-03-08T17:38:36","guid":{"rendered":"https:\/\/revistaatenea.com\/?p=292"},"modified":"2023-03-08T17:48:47","modified_gmt":"2023-03-08T17:48:47","slug":"colegio-del-estado-de-hidalgo-un-referente-para-la-ciencia-y-la-equidad-de-genero","status":"publish","type":"post","link":"https:\/\/revistaatenea.com\/index.php\/2023\/03\/08\/colegio-del-estado-de-hidalgo-un-referente-para-la-ciencia-y-la-equidad-de-genero\/","title":{"rendered":"Colegio del Estado de Hidalgo, un referente para la ciencia y la equidad de G\u00e9nero"},"content":{"rendered":"\n<p>Hablar de cambios significativos en la sociedad es un tema complejo que requiere mucho an\u00e1lisis y ciencia. El Colegio del Estado de Hidalgo, que dirige el Dr. Pablo Vargas Gonz\u00e1lez, es un recinto que desde sus comienzos tiene la misi\u00f3n de ser una instituci\u00f3n acad\u00e9mica de educaci\u00f3n e investigaci\u00f3n para contribuir al desarrollo de Hidalgo y su entorno en el contexto nacional a trav\u00e9s de los conocimientos que generen en beneficio de la sociedad.<\/p>\n\n\n\n<p>En el marco de la conmemoraci\u00f3n del d\u00eda internacional de la mujer y de su celebraci\u00f3n de 17 aniversario, el colegio del Estado de Hidalgo da de qu\u00e9 hablar como un referente para abrir espacio a las mujeres en la ciencia, creer en ellas e impulsarlas para contribuir al desarrollo de nuestro estado.<\/p>\n\n\n\n<p>El cuerpo de profesionales en la instigaci\u00f3n son en su mayor\u00eda mujeres que todos los d\u00edas dedican su tiempo a la ciencia y a buscar que sus entornos se desarrollen en mejores condiciones, donde los derechos de todas la personas sean respetados.<\/p>\n\n\n\n<p>En el colegio del Estado de Hidalgo, se reconoce la lucha por la equidad de g\u00e9nero y se suma con pol\u00edticas p\u00fablicas que protejan la integridad de todos sus alumnos desde una perspectiva de g\u00e9nero y derechos humanos, como la \u201cPol\u00edtica de Igualdad de G\u00e9nero\u201d y &#8220;Protocolo Cero Acoso y Hostigamiento Laboral y Sexual&#8221;.<\/p>\n\n\n\n<p>Lo anterior pone a esta instituci\u00f3n como un ejemplo en el avance de la ciencia en el estado, creando una red de mujeres que destacan tanto en la investigaci\u00f3n como en la docencia universitaria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hablar de cambios significativos en la sociedad es un tema complejo que requiere mucho an\u00e1lisis y ciencia. El Colegio del Estado de Hidalgo, que dirige el Dr. Pablo Vargas Gonz\u00e1lez,&hellip; <\/p>\n","protected":false},"author":5,"featured_media":293,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"two_page_speed":[],"footnotes":""},"categories":[6],"tags":[122,114,123],"class_list":["post-292","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-revista","tag-colegio-del-estado-de-hidalgo","tag-dia-de-la-mujer-2","tag-equidad-de-genero"],"_links":{"self":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts\/292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/comments?post=292"}],"version-history":[{"count":1,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts\/292\/revisions"}],"predecessor-version":[{"id":294,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts\/292\/revisions\/294"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/media\/293"}],"wp:attachment":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/media?parent=292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/categories?post=292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/tags?post=292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}