{"id":323,"date":"2023-03-11T14:02:13","date_gmt":"2023-03-11T14:02:13","guid":{"rendered":"https:\/\/revistaatenea.com\/?p=323"},"modified":"2023-03-11T14:15:46","modified_gmt":"2023-03-11T14:15:46","slug":"datos-curiosos-de-la-ceremonia-de-los-premios-oscar-2023","status":"publish","type":"post","link":"https:\/\/revistaatenea.com\/index.php\/2023\/03\/11\/datos-curiosos-de-la-ceremonia-de-los-premios-oscar-2023\/","title":{"rendered":"Datos curiosos de la ceremonia de los premios Oscar 2023"},"content":{"rendered":"\n<p>Esta noche se llevar\u00e1 a cabo la ceremonia m\u00e1s aclamada del a\u00f1o, los Oscar 2023, donde la lista de nominados ya se ha dado a conocer, pero hay algunos datos curiosos que no te puedes perder.&nbsp;<\/p>\n\n\n\n<p>En el 2022, varias cintas rompieron taquillas pero Tom Cruise es el protagonista de Top Gun: Maverick, una de las pel\u00edculas m\u00e1s taquilleras del a\u00f1o pasado y nominada al Oscar.<\/p>\n\n\n\n<h3 class=\"has-medium-font-size wp-block-heading\" style=\"font-style:normal;font-weight:400\">&#8220;Sin novedad en el frente&#8221; ya gan\u00f3 el Oscar a la mejor pel\u00edcula, esto fue casi un siglo atr\u00e1s, con la adaptaci\u00f3n de 1930 de la novela de&nbsp;Erich Maria Remarque.<\/h3>\n\n\n\n<h3 class=\"has-medium-font-size wp-block-heading\" style=\"font-style:normal;font-weight:400\">Angela Bassett es la primera persona nominada por actuar en una pel\u00edcula de universo Marvel, con su interpretaci\u00f3n de la&nbsp;reina Ramonda en &#8220;Pantera Negra: Wakanda por siempre&#8221;, lo que le mereci\u00f3 la nominaci\u00f3n a mejor actriz de reparto.<\/h3>\n\n\n\n<h3 class=\"has-medium-font-size wp-block-heading\" style=\"font-style:normal;font-weight:400\">John Williams es el nominado de mayor edad en la historia de los Oscar, a lo largo de toda su carrera, Williams ha acumulado 53 nominaciones al Oscar, lo que lo convierte en la persona viva con m\u00e1s nominaciones, y apenas a seis de&nbsp;Walt Disney que ostenta el r\u00e9cord con 59.<\/h3>\n\n\n\n<p>&nbsp;No te puedes perder esta ceremonia que se trasmitir\u00e1 en vivo desde los \u00c1ngeles, por la cadena de televisi\u00f3n TNT.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta noche se llevar\u00e1 a cabo la ceremonia m\u00e1s aclamada del a\u00f1o, los Oscar 2023, donde la lista de nominados ya se ha dado a conocer, pero hay algunos datos&hellip; <\/p>\n","protected":false},"author":4,"featured_media":324,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"two_page_speed":[],"footnotes":""},"categories":[4],"tags":[143,141],"class_list":["post-323","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tendencias","tag-premiacion","tag-premios-oscar-2023"],"_links":{"self":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts\/323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/comments?post=323"}],"version-history":[{"count":2,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts\/323\/revisions"}],"predecessor-version":[{"id":326,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts\/323\/revisions\/326"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/media\/324"}],"wp:attachment":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/media?parent=323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/categories?post=323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/tags?post=323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}