{"id":542,"date":"2023-04-11T14:46:31","date_gmt":"2023-04-11T14:46:31","guid":{"rendered":"https:\/\/revistaatenea.com\/?p=542"},"modified":"2023-04-11T14:46:33","modified_gmt":"2023-04-11T14:46:33","slug":"llega-rosalia-al-zocalo-de-la-ciudad-de-mexico","status":"publish","type":"post","link":"https:\/\/revistaatenea.com\/index.php\/2023\/04\/11\/llega-rosalia-al-zocalo-de-la-ciudad-de-mexico\/","title":{"rendered":"Llega Rosal\u00eda al Z\u00f3calo de la Ciudad de M\u00e9xico"},"content":{"rendered":"\n<p>La cantante espa\u00f1ola m\u00e1s famosa del momento, llega al Z\u00f3calo de la Ciudad de M\u00e9xico, se trata de Rosal\u00eda quien dar\u00e1 un concierto para todos los capitalinos. Esta informaci\u00f3n ha roto las redes sociales, entre comentarios, compartidos y likes.<\/p>\n\n\n\n<p>Fue Claudia Sheinbaum, jefa de gobierno de la ciudad de M\u00e9xico acompa\u00f1ada de Claudia Curiel de Icaza, secretaria de Cultura capitalina a trav\u00e9s su cuenta de TikTok, quienes informaron que ser\u00e1 el pr\u00f3ximo 28 de abril a las ocho de la noche y ser\u00e1 completamente gratuito.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"489\" src=\"https:\/\/revistaatenea.com\/wp-content\/uploads\/2023\/04\/Captura-de-Pantalla-2023-04-10-a-las-4.45.54-p.-m..png\" alt=\"\" class=\"wp-image-543\" srcset=\"https:\/\/revistaatenea.com\/wp-content\/uploads\/2023\/04\/Captura-de-Pantalla-2023-04-10-a-las-4.45.54-p.-m..png 600w, https:\/\/revistaatenea.com\/wp-content\/uploads\/2023\/04\/Captura-de-Pantalla-2023-04-10-a-las-4.45.54-p.-m.-300x245.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n\n\n<p>La noticia del concierto de Rosal\u00eda ha causado una gran emoci\u00f3n entre sus fans en M\u00e9xico, que han mostrado su entusiasmo en las redes sociales. La cantante, por su parte, a\u00fan no ha hecho ning\u00fan comentario sobre el evento en sus perfiles oficiales, pero se espera que en los pr\u00f3ximos d\u00edas haga alg\u00fan anuncio al respecto.<\/p>\n\n\n\n<p>En definitiva, el anuncio del concierto de Rosal\u00eda en TikTok demuestra c\u00f3mo esta red social se est\u00e1 consolidando como un nuevo campo de batalla para la promoci\u00f3n pol\u00edtica y cultural en M\u00e9xico y en otros pa\u00edses de la regi\u00f3n.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"696\" height=\"582\" src=\"https:\/\/revistaatenea.com\/wp-content\/uploads\/2023\/04\/Captura-de-Pantalla-2023-04-10-a-las-4.47.21-p.-m..png\" alt=\"\" class=\"wp-image-544\" srcset=\"https:\/\/revistaatenea.com\/wp-content\/uploads\/2023\/04\/Captura-de-Pantalla-2023-04-10-a-las-4.47.21-p.-m..png 696w, https:\/\/revistaatenea.com\/wp-content\/uploads\/2023\/04\/Captura-de-Pantalla-2023-04-10-a-las-4.47.21-p.-m.-300x251.png 300w, https:\/\/revistaatenea.com\/wp-content\/uploads\/2023\/04\/Captura-de-Pantalla-2023-04-10-a-las-4.47.21-p.-m.-600x502.png 600w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>La cantante espa\u00f1ola m\u00e1s famosa del momento, llega al Z\u00f3calo de la Ciudad de M\u00e9xico, se trata de Rosal\u00eda quien dar\u00e1 un concierto para todos los capitalinos. Esta informaci\u00f3n ha&hellip; <\/p>\n","protected":false},"author":5,"featured_media":545,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"two_page_speed":[],"footnotes":""},"categories":[4],"tags":[127,285,171,286],"class_list":["post-542","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tendencias","tag-ciudad-de-mexico","tag-motomami","tag-rosalia","tag-zocalo"],"_links":{"self":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts\/542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/comments?post=542"}],"version-history":[{"count":1,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts\/542\/revisions"}],"predecessor-version":[{"id":546,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts\/542\/revisions\/546"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/media\/545"}],"wp:attachment":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/media?parent=542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/categories?post=542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/tags?post=542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}