{"id":115,"count":1,"description":"","link":"https:\/\/revistaatenea.com\/index.php\/tag\/baguette\/","name":"BAGUETTE","slug":"baguette","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/tags\/115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts?tags=115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}