{"id":311,"count":1,"description":"","link":"https:\/\/revistaatenea.com\/index.php\/tag\/estreno\/","name":"estreno","slug":"estreno","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/tags\/311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts?tags=311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}