{"id":364,"count":1,"description":"","link":"https:\/\/revistaatenea.com\/index.php\/tag\/festivales\/","name":"Festivales","slug":"festivales","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/tags\/364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/revistaatenea.com\/index.php\/wp-json\/wp\/v2\/posts?tags=364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}